{"id":9632,"date":"2022-05-25T11:12:46","date_gmt":"2022-05-25T09:12:46","guid":{"rendered":"https:\/\/www.landwirt.com\/news\/?p=9632"},"modified":"2022-05-25T11:22:36","modified_gmt":"2022-05-25T09:22:36","slug":"ebermann-kommunaldienstleistungen-alles-aus-einer-hand","status":"publish","type":"post","link":"https:\/\/www.landwirt.com\/news\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\/","title":{"rendered":"Ebermann Kommunal&shy;dienst&shy;leistungen \u2013 alles aus einer Hand!"},"content":{"rendered":"\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:1.1em\"><strong>Die Firma Ebermann ist mit ihren Dienstleistungen das ganze Jahr \u00fcber im Einsatz! <\/strong><br><strong>Am Donnerstag, 2. Juni ist das Unternehmen LIVE auf dem Landwirt.com Facebook-Kanal zu sehen! Nicht verpassen!<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"252\" height=\"298\" src=\"https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/Kehrarbeiten.jpg\" alt=\"\" class=\"wp-image-9633\"\/><\/figure><\/div>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\">Kehrarbeiten<\/h3>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Ob Gehsteige, Gehwege, Parkpl\u00e4tze, Stra\u00dfen sowie alle anderen Fl\u00e4chen \u2013 Ebermann Kommunaldienstleistungen s\u00e4ubert alles.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"252\" height=\"299\" src=\"https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/Winterdienst.jpg\" alt=\"\" class=\"wp-image-9634\"\/><\/figure><\/div>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\">Winterdienst<\/h3>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Freie Stra\u00dfen sind gerade im Winter sehr wichtig. Daher bietet Firma Ebermann auch hier umfassende Dienstleistungen.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"254\" height=\"300\" src=\"https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/Umweltpflege.jpg\" alt=\"\" class=\"wp-image-9635\"\/><\/figure><\/div>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\">Umweltpflege<\/h3>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Rekultivieren, B\u00e4ume setzen und vieles mehr geh\u00f6rt zum Repertoire des Unternehmens.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"252\" height=\"298\" src=\"https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/Agrardienst.jpg\" alt=\"\" class=\"wp-image-9636\"\/><\/figure><\/div>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\">Agrardienst<\/h3>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Von der Saat bis zum Lohndrusch deckt Firma Ebermann auch hier die komplette Saison ab.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Forstmulchen<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Das Hauptaugenmerk der Firma Ebermann liegt beim Forstmulchen! Mit den besten Maschinen ausgestattet sorgen die Mitarbeiter f\u00fcr Sch\u00e4dlingsholz-Beseitigung, die Wiederaufforstung von Pflanzenfl\u00e4chen und vieles mehr.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Unternehmen bietet mit den verschiedenen Forstmulcher in den Leistungsklassen von 200 PS bis 520 PS folgende Leistungen an:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Wiederaufforstung- Vorbereitung von Pflanzenfl\u00e4chen<\/li><li>Anlegen von R\u00fcckegassen<\/li><li>Freihalten von Forststra\u00dfen beziehungsweise Versorgungsstra\u00dfen<\/li><li>Rekultivierung von Pflanzenschulen (Obst-\/ Weinbau- oder Christbaumkulturen)<\/li><li>Entbuschungsma\u00dfnahmen<\/li><li>Rodung von Baufl\u00e4chen beziehungsweisen Baugrundst\u00fccken<\/li><li>Trassenfreihaltung von Stromleitungen<\/li><li>Sch\u00e4dlingsholz Beseitigung (zum Beispiel Borkenk\u00e4ferholz oder Eschensterben)<\/li><li>Entfernen von Wurzelst\u00f6cken an der Oberfl\u00e4che<\/li><\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-extra_large\"><a href=\"https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/IMG_8314.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"729\" src=\"https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/IMG_8314-1500x729.jpg\" alt=\"\" class=\"wp-image-9640\" srcset=\"https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/IMG_8314-1500x729.jpg 1500w, https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/IMG_8314-300x146.jpg 300w, https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/IMG_8314-1030x501.jpg 1030w, https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/IMG_8314-768x373.jpg 768w, https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/IMG_8314-1536x746.jpg 1536w, https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/IMG_8314-705x343.jpg 705w, https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/IMG_8314.jpg 1599w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-entry_without_sidebar\"><a href=\"https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/44e70b08b82fad0c59c2186dde06dc2c.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"423\" src=\"https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/44e70b08b82fad0c59c2186dde06dc2c-800x423.jpg\" alt=\"\" class=\"wp-image-9638\" srcset=\"https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/44e70b08b82fad0c59c2186dde06dc2c-800x423.jpg 800w, https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/44e70b08b82fad0c59c2186dde06dc2c-710x375.jpg 710w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Als Komplettanbieter mit einzigartigem technischen Know-How, modernstem Fuhr- und Maschinenpark und getreu dem Motto \u201eALL in ONE \u2013 Alles aus einer Hand\u201c ist Ebermann Kommunaldienstleistungen ein starker regionaler Dienstleister geworden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hier geht\u2019s zu Ebermann Kommunaldienstleistungen: <a href=\"https:\/\/www.ebermann.co.at\/\">https:\/\/www.ebermann.co.at\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Firma Ebermann ist mit ihren Dienstleistungen das ganze Jahr \u00fcber im Einsatz! Am Donnerstag, 2. Juni ist das Unternehmen LIVE auf dem Landwirt.com Facebook-Kanal zu sehen! Nicht verpassen!<\/p>\n","protected":false},"author":15,"featured_media":9638,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,1],"tags":[67,69,30,461,143,386],"class_list":["post-9632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-landwirt","category-werbung","tag-forstgerate","tag-forstmaschinen","tag-forsttechnik","tag-forstwirte","tag-forstwirtschaft","tag-kommunal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ebermann Kommunal&shy;dienst&shy;leistungen \u2013 alles aus einer Hand! - Landwirt.com News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ebermann Kommunal&shy;dienst&shy;leistungen \u2013 alles aus einer Hand! - Landwirt.com News\" \/>\n<meta property=\"og:description\" content=\"Die Firma Ebermann ist mit ihren Dienstleistungen das ganze Jahr \u00fcber im Einsatz! Am Donnerstag, 2. Juni ist das Unternehmen LIVE auf dem Landwirt.com Facebook-Kanal zu sehen! Nicht verpassen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.landwirt.com\/news\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\/\" \/>\n<meta property=\"og:site_name\" content=\"Landwirt.com News\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-25T09:12:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-25T09:22:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/44e70b08b82fad0c59c2186dde06dc2c.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edith Winter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edith Winter\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\\\/\"},\"author\":{\"name\":\"Edith Winter\",\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/#\\\/schema\\\/person\\\/58b1026d44b61c2d0c39d2d1220d43e9\"},\"headline\":\"Ebermann Kommunal&shy;dienst&shy;leistungen \u2013 alles aus einer Hand!\",\"datePublished\":\"2022-05-25T09:12:46+00:00\",\"dateModified\":\"2022-05-25T09:22:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\\\/\"},\"wordCount\":244,\"publisher\":{\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/44e70b08b82fad0c59c2186dde06dc2c.jpg\",\"keywords\":[\"Forstger\u00e4te\",\"Forstmaschinen\",\"Forsttechnik\",\"Forstwirte\",\"Forstwirtschaft\",\"Kommunal\"],\"articleSection\":[\"Landwirt\",\"Werbung\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\\\/\",\"url\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\\\/\",\"name\":\"Ebermann Kommunal&shy;dienst&shy;leistungen \u2013 alles aus einer Hand! - Landwirt.com News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/44e70b08b82fad0c59c2186dde06dc2c.jpg\",\"datePublished\":\"2022-05-25T09:12:46+00:00\",\"dateModified\":\"2022-05-25T09:22:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.landwirt.com\\\/news\\\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/44e70b08b82fad0c59c2186dde06dc2c.jpg\",\"contentUrl\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/44e70b08b82fad0c59c2186dde06dc2c.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ebermann Kommunal&shy;dienst&shy;leistungen \u2013 alles aus einer Hand!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/\",\"name\":\"Landwirt.com News\",\"description\":\"Landwirt.com News\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/#organization\",\"name\":\"LANDWIRT.COM GMBH\",\"url\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/LW-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/LW-logo.png\",\"width\":250,\"height\":58,\"caption\":\"LANDWIRT.COM GMBH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/#\\\/schema\\\/person\\\/58b1026d44b61c2d0c39d2d1220d43e9\",\"name\":\"Edith Winter\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8a5aac669c36d589ec506dc09b6dcb6e1c7c0b8731e97f1f2dcea5e26e28095?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8a5aac669c36d589ec506dc09b6dcb6e1c7c0b8731e97f1f2dcea5e26e28095?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8a5aac669c36d589ec506dc09b6dcb6e1c7c0b8731e97f1f2dcea5e26e28095?s=96&d=mm&r=g\",\"caption\":\"Edith Winter\"},\"description\":\"Redakteurin f\u00fcr Zulassungsstatistiken\",\"url\":\"https:\\\/\\\/www.landwirt.com\\\/news\\\/author\\\/edith\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ebermann Kommunal&shy;dienst&shy;leistungen \u2013 alles aus einer Hand! - Landwirt.com News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Ebermann Kommunal&shy;dienst&shy;leistungen \u2013 alles aus einer Hand! - Landwirt.com News","og_description":"Die Firma Ebermann ist mit ihren Dienstleistungen das ganze Jahr \u00fcber im Einsatz! Am Donnerstag, 2. Juni ist das Unternehmen LIVE auf dem Landwirt.com Facebook-Kanal zu sehen! Nicht verpassen!","og_url":"https:\/\/www.landwirt.com\/news\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\/","og_site_name":"Landwirt.com News","article_published_time":"2022-05-25T09:12:46+00:00","article_modified_time":"2022-05-25T09:22:36+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/44e70b08b82fad0c59c2186dde06dc2c.jpg","type":"image\/jpeg"}],"author":"Edith Winter","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Edith Winter","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.landwirt.com\/news\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\/#article","isPartOf":{"@id":"https:\/\/www.landwirt.com\/news\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\/"},"author":{"name":"Edith Winter","@id":"https:\/\/www.landwirt.com\/news\/#\/schema\/person\/58b1026d44b61c2d0c39d2d1220d43e9"},"headline":"Ebermann Kommunal&shy;dienst&shy;leistungen \u2013 alles aus einer Hand!","datePublished":"2022-05-25T09:12:46+00:00","dateModified":"2022-05-25T09:22:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.landwirt.com\/news\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\/"},"wordCount":244,"publisher":{"@id":"https:\/\/www.landwirt.com\/news\/#organization"},"image":{"@id":"https:\/\/www.landwirt.com\/news\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\/#primaryimage"},"thumbnailUrl":"https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/44e70b08b82fad0c59c2186dde06dc2c.jpg","keywords":["Forstger\u00e4te","Forstmaschinen","Forsttechnik","Forstwirte","Forstwirtschaft","Kommunal"],"articleSection":["Landwirt","Werbung"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.landwirt.com\/news\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\/","url":"https:\/\/www.landwirt.com\/news\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\/","name":"Ebermann Kommunal&shy;dienst&shy;leistungen \u2013 alles aus einer Hand! - Landwirt.com News","isPartOf":{"@id":"https:\/\/www.landwirt.com\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.landwirt.com\/news\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\/#primaryimage"},"image":{"@id":"https:\/\/www.landwirt.com\/news\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\/#primaryimage"},"thumbnailUrl":"https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/44e70b08b82fad0c59c2186dde06dc2c.jpg","datePublished":"2022-05-25T09:12:46+00:00","dateModified":"2022-05-25T09:22:36+00:00","breadcrumb":{"@id":"https:\/\/www.landwirt.com\/news\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.landwirt.com\/news\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.landwirt.com\/news\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\/#primaryimage","url":"https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/44e70b08b82fad0c59c2186dde06dc2c.jpg","contentUrl":"https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2022\/05\/44e70b08b82fad0c59c2186dde06dc2c.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.landwirt.com\/news\/ebermann-kommunaldienstleistungen-alles-aus-einer-hand\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.landwirt.com\/news\/home\/"},{"@type":"ListItem","position":2,"name":"Ebermann Kommunal&shy;dienst&shy;leistungen \u2013 alles aus einer Hand!"}]},{"@type":"WebSite","@id":"https:\/\/www.landwirt.com\/news\/#website","url":"https:\/\/www.landwirt.com\/news\/","name":"Landwirt.com News","description":"Landwirt.com News","publisher":{"@id":"https:\/\/www.landwirt.com\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.landwirt.com\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.landwirt.com\/news\/#organization","name":"LANDWIRT.COM GMBH","url":"https:\/\/www.landwirt.com\/news\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.landwirt.com\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2020\/02\/LW-logo.png","contentUrl":"https:\/\/www.landwirt.com\/news\/wp-content\/uploads\/2020\/02\/LW-logo.png","width":250,"height":58,"caption":"LANDWIRT.COM GMBH"},"image":{"@id":"https:\/\/www.landwirt.com\/news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.landwirt.com\/news\/#\/schema\/person\/58b1026d44b61c2d0c39d2d1220d43e9","name":"Edith Winter","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a8a5aac669c36d589ec506dc09b6dcb6e1c7c0b8731e97f1f2dcea5e26e28095?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a8a5aac669c36d589ec506dc09b6dcb6e1c7c0b8731e97f1f2dcea5e26e28095?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8a5aac669c36d589ec506dc09b6dcb6e1c7c0b8731e97f1f2dcea5e26e28095?s=96&d=mm&r=g","caption":"Edith Winter"},"description":"Redakteurin f\u00fcr Zulassungsstatistiken","url":"https:\/\/www.landwirt.com\/news\/author\/edith\/"}]}},"_links":{"self":[{"href":"https:\/\/www.landwirt.com\/news\/wp-json\/wp\/v2\/posts\/9632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.landwirt.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.landwirt.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.landwirt.com\/news\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.landwirt.com\/news\/wp-json\/wp\/v2\/comments?post=9632"}],"version-history":[{"count":11,"href":"https:\/\/www.landwirt.com\/news\/wp-json\/wp\/v2\/posts\/9632\/revisions"}],"predecessor-version":[{"id":9651,"href":"https:\/\/www.landwirt.com\/news\/wp-json\/wp\/v2\/posts\/9632\/revisions\/9651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.landwirt.com\/news\/wp-json\/wp\/v2\/media\/9638"}],"wp:attachment":[{"href":"https:\/\/www.landwirt.com\/news\/wp-json\/wp\/v2\/media?parent=9632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.landwirt.com\/news\/wp-json\/wp\/v2\/categories?post=9632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.landwirt.com\/news\/wp-json\/wp\/v2\/tags?post=9632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}